{"id":76,"date":"2025-12-16T15:39:41","date_gmt":"2025-12-16T07:39:41","guid":{"rendered":"https:\/\/www.tstincan.com\/?page_id=76"},"modified":"2026-05-09T11:03:04","modified_gmt":"2026-05-09T03:03:04","slug":"solutions","status":"publish","type":"page","link":"https:\/\/www.tstincan.com\/fr\/solutions\/","title":{"rendered":"Solutions"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"76\" class=\"elementor elementor-76\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d78b95 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5d78b95\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac27650\" data-id=\"ac27650\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3243d27 elementor-widget elementor-widget-woocommerce-breadcrumb\" data-id=\"3243d27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-breadcrumb.default\">\n\t\t\t\t\t<nav class=\"woocommerce-breadcrumb\" aria-label=\"Breadcrumb\" data-no-translation=\"\" data-trp-gettext=\"\">Accueil<\/nav>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f786566 elementor-section-full_width elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"f786566\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0b7d50\" data-id=\"e0b7d50\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-83c6394 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83c6394\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33c818e\" data-id=\"33c818e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4291e72 elementor-widget elementor-widget-heading\" data-id=\"4291e72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e9sentation de l'usine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4fb2be elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a4fb2be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16f0a7a elementor-widget elementor-widget-text-editor\" data-id=\"16f0a7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Guangzhou Tianshi Can Making Industry Co., Ltd., \u00e9tablie en 1993, est un fabricant de bo\u00eetes m\u00e9talliques solide et technologiquement avanc\u00e9 avec 33 ans d'exp\u00e9rience dans la production de bo\u00eetes en fer-blanc. Nous sommes sp\u00e9cialis\u00e9s dans la R&amp;D, la production et la vente de bo\u00eetes en fer-blanc. Situ\u00e9e dans le district de Zengcheng, \u00e0 Guangzhou, notre entreprise couvre une superficie de plus de 1200 m\u00e8tres carr\u00e9s et dispose d'une \u00e9quipe professionnelle de plus de 100 employ\u00e9s. Nous poss\u00e9dons des ateliers de production modernes et des \u00e9quipements avanc\u00e9s de fabrication de bo\u00eetes, \u00e9quip\u00e9s d'un syst\u00e8me de d\u00e9tection de fuites enti\u00e8rement automatis\u00e9. Un taux d'inspection de 100\u202f% garantit la qualit\u00e9 des produits et automatise enti\u00e8rement le processus de fabrication des bo\u00eetes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5a9f1f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f5a9f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Activit\u00e9 principale :<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ace4a61 elementor-widget elementor-widget-text-editor\" data-id=\"ace4a61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Notre usine est sp\u00e9cialis\u00e9e dans la production de bo\u00eetes en fer-blanc de diff\u00e9rentes capacit\u00e9s et sp\u00e9cifications, adapt\u00e9es \u00e0 l'emballage de produits chimiques tels que les peintures et les lubrifiants. Nous d\u00e9veloppons, concevons, produisons et fabriquons professionnellement des bo\u00eetes en fer-blanc de diverses sp\u00e9cifications et styles pour nos clients. Nous fournissons un service de production cl\u00e9 en main pour la fabrication de bo\u00eetes en fer-blanc, incluant la fabrication de moules, la peinture, la d\u00e9coupe, l'emboutissage et l'emballage. Notre capacit\u00e9 de production mensuelle atteint 2,5 \u00e0 3 millions de bo\u00eetes. Nos produits sont largement utilis\u00e9s dans les industries chimique, des rev\u00eatements, des mat\u00e9riaux de construction et des huiles automobiles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9909ea8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9909ea8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Philosophie de l'entreprise :<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac8af74 elementor-widget elementor-widget-text-editor\" data-id=\"ac8af74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Tianshi Can Making adh\u00e8re toujours \u00e0 la philosophie de production de \u201c s\u00e9curit\u00e9, efficacit\u00e9, qualit\u00e9 et faible consommation \u201d. Ses produits sont largement utilis\u00e9s dans le domaine chimique et autres. Elle a \u00e9tabli des partenariats strat\u00e9giques \u00e0 long terme avec de nombreuses entreprises renomm\u00e9es telles que YAKOO Chemical et YATU. Son activit\u00e9 couvre le commerce int\u00e9rieur et les services d'import-export.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f8af3f0\" data-id=\"f8af3f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-049fa7d elementor-widget elementor-widget-image\" data-id=\"049fa7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/05\/\u5de5\u53821.jpg\" class=\"attachment-large size-large wp-image-4038\" alt=\"\" srcset=\"https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/05\/\u5de5\u53821.jpg 800w, https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/05\/\u5de5\u53821-300x200.jpg 300w, https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/05\/\u5de5\u53821-768x512.jpg 768w, https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/05\/\u5de5\u53821-600x400.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-503ae30 elementor-section-full_width elementor-hidden-widescreen elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"503ae30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8e9977\" data-id=\"b8e9977\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-13a6f4c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13a6f4c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d450e70\" data-id=\"d450e70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f25c68d elementor-widget elementor-widget-heading\" data-id=\"f25c68d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e9sentation de l'usine<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-911383d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"911383d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3ab17f elementor-widget elementor-widget-text-editor\" data-id=\"a3ab17f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Guangzhou Tianshi Can Making Industry Co., Ltd., \u00e9tablie en 1993, est un fabricant de bo\u00eetes m\u00e9talliques solide et technologiquement avanc\u00e9 avec 33 ans d'exp\u00e9rience dans la production de bo\u00eetes en fer-blanc. Nous sommes sp\u00e9cialis\u00e9s dans la R&amp;D, la production et la vente de bo\u00eetes en fer-blanc. Situ\u00e9e dans le district de Zengcheng, \u00e0 Guangzhou, notre entreprise couvre une superficie de plus de 1200 m\u00e8tres carr\u00e9s et dispose d'une \u00e9quipe professionnelle de plus de 100 employ\u00e9s. Nous poss\u00e9dons des ateliers de production modernes et des \u00e9quipements avanc\u00e9s de fabrication de bo\u00eetes, \u00e9quip\u00e9s d'un syst\u00e8me de d\u00e9tection de fuites enti\u00e8rement automatis\u00e9. Un taux d'inspection de 100\u202f% garantit la qualit\u00e9 des produits et automatise enti\u00e8rement le processus de fabrication des bo\u00eetes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73bc12b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"73bc12b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Activit\u00e9 principale :<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3231f74 elementor-widget elementor-widget-text-editor\" data-id=\"3231f74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous produisons professionnellement des bo\u00eetes chimiques, des bo\u00eetes de peinture, des bo\u00eetes rondes en fer-blanc et des bo\u00eetes carr\u00e9es en fer-blanc. Nous d\u00e9veloppons, concevons, produisons et fabriquons professionnellement des bo\u00eetes en fer-blanc de diverses sp\u00e9cifications et styles pour nos clients. Nous fournissons un service de production cl\u00e9 en main pour la fabrication de bo\u00eetes en fer-blanc, incluant la fabrication de moules, la peinture, la d\u00e9coupe, l'emboutissage et l'emballage. Notre capacit\u00e9 de production mensuelle atteint 2,5 \u00e0 3 millions de bo\u00eetes. Nos produits sont largement utilis\u00e9s dans les industries chimique, des rev\u00eatements, des mat\u00e9riaux de construction et des huiles automobiles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9eb01d4 elementor-widget elementor-widget-text-editor\" data-id=\"9eb01d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Guangzhou Tianshi Can Making Industry Co., Ltd., \u00e9tablie en 1993, est un fabricant de bo\u00eetes m\u00e9talliques solide et technologiquement avanc\u00e9 avec 33 ans d'exp\u00e9rience dans la production de bo\u00eetes en fer-blanc. Nous sommes sp\u00e9cialis\u00e9s dans la R&amp;D, la production et la vente de bo\u00eetes en fer-blanc. Situ\u00e9e dans le district de Zengcheng, \u00e0 Guangzhou, notre entreprise couvre une superficie de plus de 1200 m\u00e8tres carr\u00e9s et dispose d'une \u00e9quipe professionnelle de plus de 100 employ\u00e9s. Nous poss\u00e9dons des ateliers de production modernes et des \u00e9quipements avanc\u00e9s de fabrication de bo\u00eetes, \u00e9quip\u00e9s d'un syst\u00e8me de d\u00e9tection de fuites enti\u00e8rement automatis\u00e9. Un taux d'inspection de 100\u202f% garantit la qualit\u00e9 des produits et automatise enti\u00e8rement le processus de fabrication des bo\u00eetes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a13300 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6a13300\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Philosophie de l'entreprise :<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49d9eef elementor-widget elementor-widget-text-editor\" data-id=\"49d9eef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Tianshi Can Making adh\u00e8re toujours \u00e0 la philosophie de production de \u201c s\u00e9curit\u00e9, efficacit\u00e9, qualit\u00e9 et faible consommation \u201d. Ses produits sont largement utilis\u00e9s dans le domaine chimique et autres. Elle a \u00e9tabli des partenariats strat\u00e9giques \u00e0 long terme avec de nombreuses entreprises renomm\u00e9es telles que YAKOO Chemical et YATU. Son activit\u00e9 couvre le commerce int\u00e9rieur et les services d'import-export.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9393f9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9393f9a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f284b71\" data-id=\"f284b71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd99e00 elementor-widget elementor-widget-image\" data-id=\"bd99e00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/01\/about.jpg\" class=\"attachment-large size-large wp-image-2324\" alt=\"\" srcset=\"https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/01\/about.jpg 800w, https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/01\/about-300x200.jpg 300w, https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/01\/about-768x512.jpg 768w, https:\/\/www.tstincan.com\/wp-content\/uploads\/2026\/01\/about-600x400.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Factory introduction Guangzhou Tianshi Can Making Industry Co., Ltd., established in 1993, is a strong and technologically advanced hardware can manufacturer with 33 years of experience in tin can production. We specialize in the R&amp;D, production, and sales of tin cans. Located in Zengcheng District, Guangzhou, our company covers an area of over 1200 square [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-76","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.tstincan.com\/fr\/wp-json\/wp\/v2\/pages\/76","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tstincan.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tstincan.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tstincan.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tstincan.com\/fr\/wp-json\/wp\/v2\/comments?post=76"}],"version-history":[{"count":83,"href":"https:\/\/www.tstincan.com\/fr\/wp-json\/wp\/v2\/pages\/76\/revisions"}],"predecessor-version":[{"id":4074,"href":"https:\/\/www.tstincan.com\/fr\/wp-json\/wp\/v2\/pages\/76\/revisions\/4074"}],"wp:attachment":[{"href":"https:\/\/www.tstincan.com\/fr\/wp-json\/wp\/v2\/media?parent=76"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}